{"id":15102,"date":"2022-12-02T12:52:58","date_gmt":"2022-12-02T11:52:58","guid":{"rendered":"https:\/\/www.munker-interiors.com\/product\/couchtisch-aus-versteinertem-holz-mix-47\/"},"modified":"2022-12-02T12:52:58","modified_gmt":"2022-12-02T11:52:58","slug":"couchtisch-aus-versteinertem-holz-mix-47","status":"publish","type":"product","link":"https:\/\/www.munker-interiors.com\/de\/produkt\/couchtisch-aus-versteinertem-holz-mix-47\/","title":{"rendered":"Couchtisch aus versteinertem Holz &#8211; Mix"},"content":{"rendered":"<p>Jedes Mineral erzeugt seine eigene Farbe. Der Prozess des &#8220;Versteinerns&#8221; sorgt daf\u00fcr, dass alle Merkmale wie \u00c4ste, Rinde und Jahresringe des Holzes erhalten bleiben. Jeder F\u00e4ulnisprozess in der fernen Vergangenheit kann zu einer sch\u00f6nen Kristallbildung f\u00fchren, oft in mehreren Farben.<\/p>\n<p>Diese Tische sind nicht f\u00fcr den Au\u00dfenbereich geeignet und k\u00f6nnen mit einem leicht feuchten Tuch gereinigt werden. Wir empfehlen immer die Verwendung von Untersetzern f\u00fcr Ihr Glas mit Getr\u00e4nken und dergleichen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dieses sch\u00f6ne versteinerte Holzblatt ist bereits Millionen von Jahren alt. Sobald das Holz in den Boden gelangt, beginnt es sich langsam zu zersetzen und die Holzfasern kristallisieren aufgrund der Mineralien im Boden. Das Holz ist also zu einem Fossil geworden.<\/p>\n<p>Aufgrund ihrer besonderen Herkunft ist jede Tischplatte ein Unikat mit eigenen Maserungsmerkmalen und Jahresringen. <strong>Dieses Magazin ist ab dem 05.01.2023 erh\u00e4ltlich.<\/strong><\/p>\n","protected":false},"featured_media":4476,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[339,343],"product_tag":[],"class_list":["post-15102","product","type-product","status-publish","has-post-thumbnail","product_cat-couchtisch-aus-versteinertem-holz","product_cat-kaffeetisch","tm-has-options","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Couchtisch aus versteinertem Holz - Mix - Munker Versteend Hout<\/title>\n<meta name=\"description\" content=\"Bestellen Sie Ihren einzigartigen Tisch aus versteinertem Holz bei Munker Interiors! Gro\u00dfe Auswahl an versteinertem Holz! Niedrige Preise \u2713Schnelle Lieferung\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.munker-interiors.com\/de\/produkt\/couchtisch-aus-versteinertem-holz-mix-47\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Couchtisch aus versteinertem Holz - Mix - Munker Versteend Hout\" \/>\n<meta property=\"og:description\" content=\"Bestellen Sie Ihren einzigartigen Tisch aus versteinertem Holz bei Munker Interiors! Gro\u00dfe Auswahl an versteinertem Holz! Niedrige Preise \u2713Schnelle Lieferung\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.munker-interiors.com\/de\/produkt\/couchtisch-aus-versteinertem-holz-mix-47\/\" \/>\n<meta property=\"og:site_name\" content=\"Munker Versteend Hout\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.munker-interiors.com\/wp-content\/uploads\/2022\/12\/KM.096-A-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2219\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.munker-interiors.com\\\/de\\\/produkt\\\/couchtisch-aus-versteinertem-holz-mix-47\\\/\",\"url\":\"https:\\\/\\\/www.munker-interiors.com\\\/de\\\/produkt\\\/couchtisch-aus-versteinertem-holz-mix-47\\\/\",\"name\":\"Couchtisch aus versteinertem Holz - Mix - Munker Versteend Hout\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.munker-interiors.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.munker-interiors.com\\\/de\\\/produkt\\\/couchtisch-aus-versteinertem-holz-mix-47\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.munker-interiors.com\\\/de\\\/produkt\\\/couchtisch-aus-versteinertem-holz-mix-47\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.munker-interiors.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/KM.096-A-scaled.jpg\",\"datePublished\":\"2022-12-02T11:52:58+00:00\",\"description\":\"Bestellen Sie Ihren einzigartigen Tisch aus versteinertem Holz bei Munker Interiors! Gro\u00dfe Auswahl an versteinertem Holz! Niedrige Preise \u2713Schnelle Lieferung\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.munker-interiors.com\\\/de\\\/produkt\\\/couchtisch-aus-versteinertem-holz-mix-47\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.munker-interiors.com\\\/de\\\/produkt\\\/couchtisch-aus-versteinertem-holz-mix-47\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.munker-interiors.com\\\/de\\\/produkt\\\/couchtisch-aus-versteinertem-holz-mix-47\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.munker-interiors.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/KM.096-A-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.munker-interiors.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/KM.096-A-scaled.jpg\",\"width\":2560,\"height\":2219,\"caption\":\"Couchtisch aus versteinertem Holz\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.munker-interiors.com\\\/de\\\/produkt\\\/couchtisch-aus-versteinertem-holz-mix-47\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.munker-interiors.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Winkel\",\"item\":\"https:\\\/\\\/www.munker-interiors.com\\\/nl\\\/winkel\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Couchtisch aus versteinertem Holz &#8211; Mix\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.munker-interiors.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.munker-interiors.com\\\/de\\\/\",\"name\":\"Munker Versteend Hout\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.munker-interiors.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.munker-interiors.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.munker-interiors.com\\\/de\\\/#organization\",\"name\":\"Munker Versteend Hout\",\"url\":\"https:\\\/\\\/www.munker-interiors.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.munker-interiors.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.munker-interiors.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/vector-01-1-1.svg\",\"contentUrl\":\"https:\\\/\\\/www.munker-interiors.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/vector-01-1-1.svg\",\"caption\":\"Munker Versteend Hout\"},\"image\":{\"@id\":\"https:\\\/\\\/www.munker-interiors.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Couchtisch aus versteinertem Holz - Mix - Munker Versteend Hout","description":"Bestellen Sie Ihren einzigartigen Tisch aus versteinertem Holz bei Munker Interiors! Gro\u00dfe Auswahl an versteinertem Holz! Niedrige Preise \u2713Schnelle Lieferung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.munker-interiors.com\/de\/produkt\/couchtisch-aus-versteinertem-holz-mix-47\/","og_locale":"de_DE","og_type":"article","og_title":"Couchtisch aus versteinertem Holz - Mix - Munker Versteend Hout","og_description":"Bestellen Sie Ihren einzigartigen Tisch aus versteinertem Holz bei Munker Interiors! Gro\u00dfe Auswahl an versteinertem Holz! Niedrige Preise \u2713Schnelle Lieferung","og_url":"https:\/\/www.munker-interiors.com\/de\/produkt\/couchtisch-aus-versteinertem-holz-mix-47\/","og_site_name":"Munker Versteend Hout","og_image":[{"width":2560,"height":2219,"url":"https:\/\/www.munker-interiors.com\/wp-content\/uploads\/2022\/12\/KM.096-A-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.munker-interiors.com\/de\/produkt\/couchtisch-aus-versteinertem-holz-mix-47\/","url":"https:\/\/www.munker-interiors.com\/de\/produkt\/couchtisch-aus-versteinertem-holz-mix-47\/","name":"Couchtisch aus versteinertem Holz - Mix - Munker Versteend Hout","isPartOf":{"@id":"https:\/\/www.munker-interiors.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.munker-interiors.com\/de\/produkt\/couchtisch-aus-versteinertem-holz-mix-47\/#primaryimage"},"image":{"@id":"https:\/\/www.munker-interiors.com\/de\/produkt\/couchtisch-aus-versteinertem-holz-mix-47\/#primaryimage"},"thumbnailUrl":"https:\/\/www.munker-interiors.com\/wp-content\/uploads\/2022\/12\/KM.096-A-scaled.jpg","datePublished":"2022-12-02T11:52:58+00:00","description":"Bestellen Sie Ihren einzigartigen Tisch aus versteinertem Holz bei Munker Interiors! Gro\u00dfe Auswahl an versteinertem Holz! Niedrige Preise \u2713Schnelle Lieferung","breadcrumb":{"@id":"https:\/\/www.munker-interiors.com\/de\/produkt\/couchtisch-aus-versteinertem-holz-mix-47\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.munker-interiors.com\/de\/produkt\/couchtisch-aus-versteinertem-holz-mix-47\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.munker-interiors.com\/de\/produkt\/couchtisch-aus-versteinertem-holz-mix-47\/#primaryimage","url":"https:\/\/www.munker-interiors.com\/wp-content\/uploads\/2022\/12\/KM.096-A-scaled.jpg","contentUrl":"https:\/\/www.munker-interiors.com\/wp-content\/uploads\/2022\/12\/KM.096-A-scaled.jpg","width":2560,"height":2219,"caption":"Couchtisch aus versteinertem Holz"},{"@type":"BreadcrumbList","@id":"https:\/\/www.munker-interiors.com\/de\/produkt\/couchtisch-aus-versteinertem-holz-mix-47\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.munker-interiors.com\/de\/"},{"@type":"ListItem","position":2,"name":"Winkel","item":"https:\/\/www.munker-interiors.com\/nl\/winkel\/"},{"@type":"ListItem","position":3,"name":"Couchtisch aus versteinertem Holz &#8211; Mix"}]},{"@type":"WebSite","@id":"https:\/\/www.munker-interiors.com\/de\/#website","url":"https:\/\/www.munker-interiors.com\/de\/","name":"Munker Versteend Hout","description":"","publisher":{"@id":"https:\/\/www.munker-interiors.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.munker-interiors.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.munker-interiors.com\/de\/#organization","name":"Munker Versteend Hout","url":"https:\/\/www.munker-interiors.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.munker-interiors.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.munker-interiors.com\/wp-content\/uploads\/2022\/04\/vector-01-1-1.svg","contentUrl":"https:\/\/www.munker-interiors.com\/wp-content\/uploads\/2022\/04\/vector-01-1-1.svg","caption":"Munker Versteend Hout"},"image":{"@id":"https:\/\/www.munker-interiors.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.munker-interiors.com\/de\/wp-json\/wp\/v2\/product\/15102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.munker-interiors.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.munker-interiors.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.munker-interiors.com\/de\/wp-json\/wp\/v2\/comments?post=15102"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.munker-interiors.com\/de\/wp-json\/wp\/v2\/media\/4476"}],"wp:attachment":[{"href":"https:\/\/www.munker-interiors.com\/de\/wp-json\/wp\/v2\/media?parent=15102"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.munker-interiors.com\/de\/wp-json\/wp\/v2\/product_brand?post=15102"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.munker-interiors.com\/de\/wp-json\/wp\/v2\/product_cat?post=15102"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.munker-interiors.com\/de\/wp-json\/wp\/v2\/product_tag?post=15102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}